{"id":7,"date":"2021-04-20T10:34:19","date_gmt":"2021-04-20T08:34:19","guid":{"rendered":"http:\/\/www.avioninternational.com\/en\/home\/"},"modified":"2024-05-07T12:06:08","modified_gmt":"2024-05-07T10:06:08","slug":"home","status":"publish","type":"page","link":"https:\/\/www.avioninternational.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":-1,"comment_status":"closed","ping_status":"closed","template":"template-home.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>International Freight Forwarding | Customs Services | Avion<\/title>\n<meta name=\"description\" content=\"Avion is a company offering comprehensive international freight forwarding and customs clearance consultancy services.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.avioninternational.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"International Freight Forwarding | Customs Services | Avion\" \/>\n<meta property=\"og:description\" content=\"Avion is a company offering comprehensive international freight forwarding and customs clearance consultancy services.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.avioninternational.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Avion en\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T10:06:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.avioninternational.com\/en\/#organization\",\"name\":\"Avion Company\",\"url\":\"https:\/\/www.avioninternational.com\/en\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.avioninternational.com\/en\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.avioninternational.com\/en\/wp-content\/uploads\/sites\/2\/android-icon-192x192-1.png\",\"contentUrl\":\"https:\/\/www.avioninternational.com\/en\/wp-content\/uploads\/sites\/2\/android-icon-192x192-1.png\",\"width\":192,\"height\":192,\"caption\":\"Avion Company\"},\"image\":{\"@id\":\"https:\/\/www.avioninternational.com\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.avioninternational.com\/en\/#website\",\"url\":\"https:\/\/www.avioninternational.com\/en\/\",\"name\":\"Avion en\",\"description\":\"International Freight Forwarder\",\"publisher\":{\"@id\":\"https:\/\/www.avioninternational.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.avioninternational.com\/en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.avioninternational.com\/en\/#webpage\",\"url\":\"https:\/\/www.avioninternational.com\/en\/\",\"name\":\"International Freight Forwarding | Customs Services | Avion\",\"isPartOf\":{\"@id\":\"https:\/\/www.avioninternational.com\/en\/#website\"},\"datePublished\":\"2021-04-20T08:34:19+00:00\",\"dateModified\":\"2024-05-07T10:06:08+00:00\",\"description\":\"Avion is a company offering comprehensive international freight forwarding and customs clearance consultancy services.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.avioninternational.com\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.avioninternational.com\/en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.avioninternational.com\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.avioninternational.com\/en\/\",\"url\":\"https:\/\/www.avioninternational.com\/en\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.avioninternational.com\/en\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.avioninternational.com\/en\/wp-json\/wp\/v2\/pages\/7"}],"collection":[{"href":"https:\/\/www.avioninternational.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.avioninternational.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.avioninternational.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.avioninternational.com\/en\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":51,"href":"https:\/\/www.avioninternational.com\/en\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":2402,"href":"https:\/\/www.avioninternational.com\/en\/wp-json\/wp\/v2\/pages\/7\/revisions\/2402"}],"wp:attachment":[{"href":"https:\/\/www.avioninternational.com\/en\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}